{"id":3254,"date":"2021-07-19T15:06:00","date_gmt":"2021-07-19T13:06:00","guid":{"rendered":"https:\/\/www.naschomutov.cz\/naschomutov\/?p=3254"},"modified":"2025-01-21T19:31:23","modified_gmt":"2025-01-21T18:31:23","slug":"4-hriste-pro-seniory-a-odpocinkova-zona-bezrucova","status":"publish","type":"post","link":"https:\/\/www.naschomutov.cz\/naschomutov\/4-hriste-pro-seniory-a-odpocinkova-zona-bezrucova\/","title":{"rendered":"4. H\u0159i\u0161t\u011b pro seniory a odpo\u010dinkov\u00e1 z\u00f3na Bezru\u010dova"},"content":{"rendered":"<p>C\u00edlem projektu bylo vybudovat v zeleni mezi Bezru\u010dovou ulic\u00ed a \u0159ekou Chomutovkou aktivn\u00ed a z\u00e1rove\u0148 odpo\u010dinkov\u00e9 m\u00edsto s lavi\u010dkami zejm\u00e9na pro seniory, kte\u0159\u00ed bydl\u00ed v okol\u00ed Horn\u00ed vsi nebo v dom\u011b s pe\u010dovatelskou slu\u017ebou Merkur. Na konci \u010dervna 2022 se na m\u00edsto do tr\u00e1vy instalovalo 5 fitness stroj\u016f. Pot\u00e9 se kolem nich vytvo\u0159il mlatov\u00fd povrch. Do prostoru se nov\u011b zhotovila i p\u0159\u00edstupov\u00e1 cesti\u010dka z mlatov\u00e9ho povrchu a p\u00e9tanque h\u0159i\u0161t\u011b. Instalovaly se sem i komfortn\u00ed lavi\u010dky s podru\u010dkami a s takovou ergonomi\u00ed pro snaz\u0161\u00ed used\u00e1n\u00ed a vst\u00e1v\u00e1n\u00ed. V oblouku za lavi\u010dkami u velk\u00e9 l\u00edpy byly vys\u00e1zeny trsy okrasn\u00fdch travin, kter\u00e9 na ja\u0159e dokresl\u00ed klidov\u00fd prostor.<\/p>\n<p>Snahou je udr\u017eet seniory co nejd\u00e9le vit\u00e1ln\u00ed a fit. Pokud star\u0161\u00ed lid\u00e9 cvi\u010d\u00ed, jsou zdrav\u011bj\u0161\u00ed. St\u00e1le v\u00edce studi\u00ed ukazuje, \u017ee senio\u0159i ale nepot\u0159ebuj\u00ed jen cvi\u010den\u00ed, ale tak\u00e9 soci\u00e1ln\u00ed kontakt a p\u0159\u00edrodu. Prvky pro zdokonalov\u00e1n\u00ed udr\u017een\u00ed rovnov\u00e1hy a procvi\u010dov\u00e1n\u00ed obratnosti byly vybr\u00e1ny spolu s odborn\u00edky z pe\u010dovatelsk\u00e9ho domu.<\/p>\n<p><u>N\u00e1klady:<\/u> 600 tis. K\u010d<br \/>\n<u>Navrhovatel:<\/u> Lib\u011bna \u0160m\u00eddov\u00e1, Nina Furiakov\u00e1<\/p>\n<p><u>P\u016fvodn\u00ed foto n\u00e1vrhu:<\/u><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-3255\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2021\/07\/vitezny-navrh-c.-4-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2021\/07\/vitezny-navrh-c.-4-300x200.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2021\/07\/vitezny-navrh-c.-4-768x512.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2021\/07\/vitezny-navrh-c.-4.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><u>Foto z realizace:<\/u><\/p>\n<div id='gallery-1' class='gallery galleryid-3254 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075136-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075136-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075136-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075136-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075136-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075136-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075136-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075212-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075212-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075212-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075212-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075212-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075212-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075212-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075140-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075140-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075140-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075140-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075140-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075140-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075140-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075156-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075156-002-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075156-002-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075156-002-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075156-002-1152x1536.jpg 1152w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075156-002-1536x2048.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075156-002-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075201-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075201-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075201-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075201-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075201-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075201-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_075201-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095346-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095346-002-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095346-002-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095346-002-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095346-002-1152x1536.jpg 1152w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095346-002-1536x2048.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095346-002-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095919-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095919-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095919-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095919-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095919-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095919-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_095919-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_100053-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_100053-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_100053-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_100053-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_100053-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_100053-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220919_100053-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092311-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092311-002-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092311-002-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092311-002-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092311-002-1152x1536.jpg 1152w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092311-002-1536x2048.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092311-002-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092521-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092521-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092521-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092521-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092521-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092521-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092521-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092536-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092536-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092536-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092536-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092536-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092536-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092536-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092549-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092549-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092549-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092549-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092549-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092549-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092549-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092709-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092709-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092709-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092709-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092709-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092709-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092709-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092727-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092727-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092727-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092727-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092727-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092727-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_092727-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093807-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093807-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093807-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093807-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093807-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093807-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093807-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093814-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093814-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093814-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093814-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093814-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093814-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_093814-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183846-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183846-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183846-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183846-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183846-1152x1536.jpg 1152w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183846-1536x2048.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183846-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183942-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183942-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183942-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183942-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183942-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183942-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183942-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183949-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183949-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183949-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183949-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183949-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183949-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183949-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183955-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183955-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183955-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183955-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183955-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183955-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220921_183955-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075151-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075151-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075151-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075151-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075151-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075151-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075151-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075157-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075157-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075157-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075157-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075157-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075157-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075157-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075200-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075200-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075200-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075200-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075200-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075200-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075200-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075210-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075210-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075210-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075210-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075210-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075210-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075210-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075219-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075219-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075219-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075219-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075219-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075219-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075219-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075238-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075238-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075238-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075238-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075238-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075238-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075238-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075304-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075304-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075304-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075304-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075304-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075304-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075304-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075343-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075343-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075343-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075343-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075343-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075343-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075343-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075854-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075854-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075854-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075854-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075854-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075854-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075854-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075857-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075857-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075857-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075857-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075857-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075857-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220922_075857-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_6-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_6-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_6-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_6-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_6-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_6.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_1-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_1-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_1-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_1-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_1.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_2-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_2-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_2-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_2-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_2-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_2.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_3-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_3-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_3-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_3-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_3-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_3.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_4-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_4-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_4-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_4-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_4-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_4.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_5-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_5-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_5-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_5-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_5-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/na-web_5.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075219-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075219-002-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075219-002-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075219-002-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075219-002-1152x1536.jpg 1152w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075219-002-1536x2048.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075219-002-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075249-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075249-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075249-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075249-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075249-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075249-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220926_075249-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130712-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130712-002-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130712-002-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130712-002-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130712-002-1152x1536.jpg 1152w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130712-002-1536x2048.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130712-002-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130724-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130724-002-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130724-002-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130724-002-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130724-002-1152x1536.jpg 1152w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130724-002-1536x2048.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130724-002-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130743-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130743-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130743-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130743-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130743-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130743-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20220927_130743-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_14.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_14-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_14-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_14-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_14-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_14-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_14.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_2-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_2-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_2-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_2-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_2-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_2.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_3-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_3-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_3-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_3-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_3-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_3.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_5-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_5-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_5-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_5-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_5-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_5.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_7-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_7-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_7-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_7.jpg 1024w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_8-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_8-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_8-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_8.jpg 1024w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_9.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_9-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_9-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_9-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_9-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_9-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_9.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_10.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_10-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_10-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_10-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_10-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_10-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_10.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_11-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_11-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_11-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_11.jpg 1024w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_15.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_15-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_15-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_15-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_15-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_15-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_15.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_18.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_18-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_18-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_18-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_18-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_18-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_18.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_19.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_19-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_19-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_19-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/24.10.2022_19.jpg 1024w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/1024-1365-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/1024-1365-2-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/1024-1365-2-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/1024-1365-2-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/1024-1365-2.jpg 1024w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/2048-1536-max.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/2048-1536-max-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/2048-1536-max-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/2048-1536-max-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/2048-1536-max-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/2048-1536-max-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/2048-1536-max.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081034-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081034-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081034-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081034-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081034-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081034-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081034-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081049-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081049-002-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081049-002-300x225.jpg 300w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081049-002-1024x768.jpg 1024w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081049-002-768x576.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081049-002-1536x1152.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081049-002-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081341-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081341-002-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081341-002-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081341-002-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081341-002-1152x1536.jpg 1152w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081341-002-1536x2048.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081341-002-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081426-002-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081426-002-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081426-002-225x300.jpg 225w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081426-002-768x1024.jpg 768w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081426-002-1152x1536.jpg 1152w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081426-002-1536x2048.jpg 1536w, https:\/\/www.naschomutov.cz\/naschomutov\/wp-content\/uploads\/2022\/09\/IMG_20221130_081426-002-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00edlem projektu bylo vybudovat v zeleni mezi Bezru\u010dovou ulic\u00ed a \u0159ekou Chomutovkou aktivn\u00ed a z\u00e1rove\u0148 odpo\u010dinkov\u00e9 m\u00edsto s lavi\u010dkami zejm\u00e9na [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3490,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[16],"tags":[],"class_list":["post-3254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-navrhy-2021"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.naschomutov.cz\/naschomutov\/wp-json\/wp\/v2\/posts\/3254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naschomutov.cz\/naschomutov\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naschomutov.cz\/naschomutov\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naschomutov.cz\/naschomutov\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naschomutov.cz\/naschomutov\/wp-json\/wp\/v2\/comments?post=3254"}],"version-history":[{"count":12,"href":"https:\/\/www.naschomutov.cz\/naschomutov\/wp-json\/wp\/v2\/posts\/3254\/revisions"}],"predecessor-version":[{"id":4434,"href":"https:\/\/www.naschomutov.cz\/naschomutov\/wp-json\/wp\/v2\/posts\/3254\/revisions\/4434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naschomutov.cz\/naschomutov\/wp-json\/wp\/v2\/media\/3490"}],"wp:attachment":[{"href":"https:\/\/www.naschomutov.cz\/naschomutov\/wp-json\/wp\/v2\/media?parent=3254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naschomutov.cz\/naschomutov\/wp-json\/wp\/v2\/categories?post=3254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naschomutov.cz\/naschomutov\/wp-json\/wp\/v2\/tags?post=3254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}